{"id":9014,"date":"2024-10-25T16:13:44","date_gmt":"2024-10-25T14:13:44","guid":{"rendered":"https:\/\/www.oliorivieraligure.it\/?p=9014"},"modified":"2024-10-25T16:15:48","modified_gmt":"2024-10-25T14:15:48","slug":"olioliva-appuntamento-a-imperia","status":"publish","type":"post","link":"https:\/\/www.oliorivieraligure.it\/en\/news\/olioliva-appuntamento-a-imperia\/","title":{"rendered":"Olioliva, appuntamento a Imperia"},"content":{"rendered":"\n<p>A Imperia, da venerd\u00ec 8 a domenica 10 novembre,\u00a0 si rinnova l\u2019appuntamento con Olioliva, la Festa dell\u2019Olio Nuovo, giunta alla 24<sup>a<\/sup> edizione. Presso lo stand Orgoglio Liguria, in Calata Cuneo, sul porto di Oneglia,\u00a0 grazie al Consorzio di tutela dell\u2019olio extra vergine di oliva Riviera Ligure DOP sar\u00e0 possibile scoprire le diverse produzioni territoriali: Taggiasca, Arnasca, Lavagnina e Razzola, le principali variet\u00e0 della nostra regione. Quattro profili sensoriali di oli in cui il contrassegno giallo numerato del Consorzio significa origine, tradizione, qualit\u00e0.<\/p>\n\n\n\n<p>Sono oli che rispettano il disciplinare di produzione, sottoposti a controlli e verifiche qualitative per la garanzia del consumatore.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Arnasca.jpeg?resize=900%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-9016\" srcset=\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Arnasca.jpeg?resize=900%2C900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Arnasca.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Arnasca.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Arnasca.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Arnasca.jpeg?resize=700%2C700&amp;ssl=1 700w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Arnasca.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Lavagnina.jpeg?resize=900%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-9017\" srcset=\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Lavagnina.jpeg?resize=900%2C900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Lavagnina.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Lavagnina.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Lavagnina.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Lavagnina.jpeg?resize=700%2C700&amp;ssl=1 700w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Lavagnina.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Razzola.jpeg?resize=900%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-9019\" srcset=\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Razzola.jpeg?resize=900%2C900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Razzola.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Razzola.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Razzola.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Razzola.jpeg?resize=700%2C700&amp;ssl=1 700w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Razzola.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Taggiasca.jpeg?resize=900%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-9020\" srcset=\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Taggiasca.jpeg?resize=900%2C900&amp;ssl=1 900w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Taggiasca.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Taggiasca.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Taggiasca.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Taggiasca.jpeg?resize=700%2C700&amp;ssl=1 700w, https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Taggiasca.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Imperia, da venerd\u00ec 8 a domenica 10 novembre,\u00a0 si rinnova l\u2019appuntamento con Olioliva, la Festa dell\u2019Olio Nuovo, giunta alla 24a edizione. Presso lo stand Orgoglio Liguria, in Calata Cuneo, sul porto di Oneglia,\u00a0 grazie al Consorzio di tutela dell\u2019olio extra vergine di oliva Riviera Ligure DOP sar\u00e0 possibile scoprire le diverse produzioni territoriali: Taggiasca, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":9008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":{"0":"post-9014","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title><\/title>\n<meta name=\"description\" content=\"A Imperia, da venerd\u00ec 8 a domenica 10 novembre,\u00a0 si rinnova l\u2019appuntamento con Olioliva, la Festa dell\u2019Olio Nuovo, giunta alla 24a edizione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alessandro Giacobbe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/\"},\"author\":{\"name\":\"Alessandro Giacobbe\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/#\/schema\/person\/ea22ed2165681d8668134e18b3802ce7\"},\"headline\":\"Olioliva, appuntamento a Imperia\",\"datePublished\":\"2024-10-25T14:13:44+00:00\",\"dateModified\":\"2024-10-25T14:15:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/\"},\"wordCount\":107,\"publisher\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/\",\"url\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/\",\"name\":\"[:it]Olioliva, appuntamento a Imperia[:] - Consorzio di Tutela Olio DOP Riviera Ligure\",\"isPartOf\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1\",\"datePublished\":\"2024-10-25T14:13:44+00:00\",\"dateModified\":\"2024-10-25T14:15:48+00:00\",\"description\":\"A Imperia, da venerd\u00ec 8 a domenica 10 novembre,\u00a0 si rinnova l\u2019appuntamento con Olioliva, la Festa dell\u2019Olio Nuovo, giunta alla 24a edizione.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1\",\"width\":522,\"height\":393,\"caption\":\"L'invaiatura procede lentamente nell'oliveto dimostrativo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.oliorivieraligure.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Olioliva, appuntamento a Imperia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/#website\",\"url\":\"https:\/\/www.oliorivieraligure.it\/\",\"name\":\"Consorzio di Tutela Olio DOP Riviera Ligure\",\"description\":\"Tutta la nostra passione da sempre. Naturalmente.\",\"publisher\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oliorivieraligure.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/#organization\",\"name\":\"Consorzio per la Tutela dell'Olio DOP Riviera Ligure\",\"url\":\"https:\/\/www.oliorivieraligure.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i2.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2016\/11\/logoconsorzio.jpg?fit=1040%2C520&ssl=1\",\"contentUrl\":\"https:\/\/i2.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2016\/11\/logoconsorzio.jpg?fit=1040%2C520&ssl=1\",\"width\":1040,\"height\":520,\"caption\":\"Consorzio per la Tutela dell'Olio DOP Riviera Ligure\"},\"image\":{\"@id\":\"https:\/\/www.oliorivieraligure.it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oliorivieraligure.it\/#\/schema\/person\/ea22ed2165681d8668134e18b3802ce7\",\"name\":\"Alessandro Giacobbe\",\"url\":\"https:\/\/www.oliorivieraligure.it\/en\/author\/agiacobbe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:it]Olioliva, appuntamento a Imperia[:] - Consorzio di Tutela Olio DOP Riviera Ligure","description":"A Imperia, da venerd\u00ec 8 a domenica 10 novembre,\u00a0 si rinnova l\u2019appuntamento con Olioliva, la Festa dell\u2019Olio Nuovo, giunta alla 24a edizione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/","twitter_misc":{"Written by":"Alessandro Giacobbe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#article","isPartOf":{"@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/"},"author":{"name":"Alessandro Giacobbe","@id":"https:\/\/www.oliorivieraligure.it\/#\/schema\/person\/ea22ed2165681d8668134e18b3802ce7"},"headline":"Olioliva, appuntamento a Imperia","datePublished":"2024-10-25T14:13:44+00:00","dateModified":"2024-10-25T14:15:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/"},"wordCount":107,"publisher":{"@id":"https:\/\/www.oliorivieraligure.it\/#organization"},"image":{"@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/","url":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/","name":"[:it]Olioliva, appuntamento a Imperia[:] - Consorzio di Tutela Olio DOP Riviera Ligure","isPartOf":{"@id":"https:\/\/www.oliorivieraligure.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#primaryimage"},"image":{"@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1","datePublished":"2024-10-25T14:13:44+00:00","dateModified":"2024-10-25T14:15:48+00:00","description":"A Imperia, da venerd\u00ec 8 a domenica 10 novembre,\u00a0 si rinnova l\u2019appuntamento con Olioliva, la Festa dell\u2019Olio Nuovo, giunta alla 24a edizione.","breadcrumb":{"@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#primaryimage","url":"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1","width":522,"height":393,"caption":"L'invaiatura procede lentamente nell'oliveto dimostrativo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.oliorivieraligure.it\/news\/olioliva-appuntamento-a-imperia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.oliorivieraligure.it\/"},{"@type":"ListItem","position":2,"name":"Olioliva, appuntamento a Imperia"}]},{"@type":"WebSite","@id":"https:\/\/www.oliorivieraligure.it\/#website","url":"https:\/\/www.oliorivieraligure.it\/","name":"Consorzio di Tutela Olio DOP Riviera Ligure","description":"Tutta la nostra passione da sempre. Naturalmente.","publisher":{"@id":"https:\/\/www.oliorivieraligure.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oliorivieraligure.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.oliorivieraligure.it\/#organization","name":"Consorzio per la Tutela dell'Olio DOP Riviera Ligure","url":"https:\/\/www.oliorivieraligure.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.oliorivieraligure.it\/#\/schema\/logo\/image\/","url":"https:\/\/i2.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2016\/11\/logoconsorzio.jpg?fit=1040%2C520&ssl=1","contentUrl":"https:\/\/i2.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2016\/11\/logoconsorzio.jpg?fit=1040%2C520&ssl=1","width":1040,"height":520,"caption":"Consorzio per la Tutela dell'Olio DOP Riviera Ligure"},"image":{"@id":"https:\/\/www.oliorivieraligure.it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.oliorivieraligure.it\/#\/schema\/person\/ea22ed2165681d8668134e18b3802ce7","name":"Alessandro Giacobbe","url":"https:\/\/www.oliorivieraligure.it\/en\/author\/agiacobbe\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.oliorivieraligure.it\/wp-content\/uploads\/2024\/10\/Linvaiatura-procede-lentamente-nelloliveto-dimostrativo.jpg?fit=522%2C393&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p1pXCP-2lo","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/posts\/9014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/comments?post=9014"}],"version-history":[{"count":2,"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/posts\/9014\/revisions"}],"predecessor-version":[{"id":9021,"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/posts\/9014\/revisions\/9021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/media\/9008"}],"wp:attachment":[{"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/media?parent=9014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/categories?post=9014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oliorivieraligure.it\/en\/wp-json\/wp\/v2\/tags?post=9014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}